{"id":33244,"date":"2024-10-02T00:00:00","date_gmt":"2024-10-01T22:00:00","guid":{"rendered":"https:\/\/ardor-realestate.com\/nekretnina\/otok-krk-tribulje-zemljiste-sa-projektom-objekti-c1-i-c2\/"},"modified":"2025-12-12T18:14:52","modified_gmt":"2025-12-12T17:14:52","slug":"isola-di-krk-tribulje-terreno-con-edifici-di-progetto-c1-e-c2","status":"publish","type":"property","link":"https:\/\/ardor-realestate.com\/it\/immobiliare\/isola-di-krk-tribulje-terreno-con-edifici-di-progetto-c1-e-c2\/","title":{"rendered":"Isola di Krk, Tribulje, terreno con progetto, edifici C1 e C2"},"content":{"rendered":"<div id=\"hrvatski\">L&#039;isola di Veglia, Tribulje, un luogo la cui bellezza \u00e8 stata decantata fin dalla fine del XV secolo, \u00e8 sempre stata un rifugio per chi cercava pace e tranquillit\u00e0, ma desiderava anche essere vicino alle attrazioni turistiche. Grazie alla sua importanza storica, \u00e8 menzionata in molti scritti glagolitici ed \u00e8 diventata la casa di molti nuovi residenti che apprezzano l&#039;autenticit\u00e0, la bellezza e la pace di questa citt\u00e0 costiera.<\/p>\n<p>Terreno edificabile di 989,8 m\u00b2 con progetto presentato per l&#039;ottenimento del permesso di costruire. Ciascuna delle due unit\u00e0 abitative di questa lussuosa villa dispone di piscina privata, terrazza esterna coperta, giardino, diversi posti auto e cantina.<\/p>\n<p>La casa C1 ha una superficie abitabile totale di 231,18 m\u00b2. Il piano terra \u00e8 composto da cucina, soggiorno e una camera da letto con bagno, mentre il primo piano, di 69,68 m\u00b2, ospita due camere da letto, due bagni e una terrazza coperta con vista mare.<br \/>\nL&#039;abitazione C2 ha una superficie abitabile totale di 232,12 m\u00b2. Al piano terra, su una superficie di 99,60 m\u00b2, si trovano una cucina, un soggiorno e una camera da letto con bagno, mentre al primo piano, su una superficie di 70,30 m\u00b2, si trovano altre tre camere da letto e due bagni.<\/p>\n<p>Gentili clienti, in conformit\u00e0 con la legge sull&#039;intermediazione immobiliare, la visione dell&#039;immobile \u00e8 possibile solo con la firma del contratto di intermediazione. Secondo lo stesso, l&#039;acquirente \u00e8 tenuto a pagare la commissione d&#039;agenzia in caso di acquisto.<\/p>\n<p>CODICE ID AGENZIA: 2173<\/p>\n<p>Sendi Vinski<br \/>\nAgente autorizzato<br \/>\nCellulare: 0038598443289<br \/>\nTelefono: 0038551222673<br \/>\nE-mail: prodaja@ardor-realestate.com<br \/>\nwww.ardor-realestate.com<\/p><\/div>\n<div id=\"engleski\">L&#039;isola di Veglia, Tribulje, un luogo la cui bellezza \u00e8 stata decantata fin dalla fine del XV secolo, \u00e8 sempre stata un rifugio per chi cerca pace e tranquillit\u00e0, ma desidera essere vicino alle attrazioni turistiche. Grazie alla sua importanza storica, \u00e8 menzionata in molti scritti glagolitici ed \u00e8 diventata la casa di molti nuovi residenti che apprezzano l&#039;autenticit\u00e0, la bellezza e la pace di questo luogo di mare.<\/p>\n<p>Terreno edificabile di 989,8 m\u00b2 con progetto presentato per l&#039;ottenimento del permesso di costruire. Ciascuna delle due unit\u00e0 abitative di questa lussuosa villa dispone di piscina privata, terrazza esterna coperta, giardino, diversi posti auto e cantina.<\/p>\n<p>L&#039;abitazione C1 si estende su una superficie abitabile totale di 231,18 m\u00b2. Al piano terra si trovano una cucina, un soggiorno e una camera da letto con bagno, mentre al primo piano, di 69,68 m\u00b2, si trovano due camere, due bagni e una terrazza coperta con vista mare.<br \/>\nL&#039;abitazione C2 ha una superficie abitabile totale di 232,12 m\u00b2. Al piano terra, di 99,60 m\u00b2, si trovano una cucina, un soggiorno e una camera da letto con bagno, mentre al primo piano, di 70,30 m\u00b2, si trovano altre tre camere da letto e due bagni.<\/p>\n<p>Gentili clienti, ai sensi della Legge sulla Mediazione nelle Transazioni Immobiliari, la visita dell&#039;immobile \u00e8 possibile solo previa firma del Contratto di Mediazione. Ai sensi dello stesso, l&#039;acquirente \u00e8 tenuto a pagare la provvigione d&#039;agenzia in caso di acquisto.<\/p>\n<p>CODICE ID: 2173<\/p>\n<p>Sendi Vinski<br \/>\nAgente autorizzato<br \/>\nCellulare: 0038598443289<br \/>\nTelefono: 0038551222673<br \/>\nE-mail: prodaja@ardor-realestate.com<br \/>\nwww.ardor-realestate.com<\/p><\/div>\n<div id=\"italijanski\">L&#8217;isola di Krk, Tribulje, un luogo della cui bellezza si parla gi\u00e0 dalla fine del XV secolo, \u00e8 sempre stata un rifugio per coloro che cercano pace e tranquillit\u00e0, ma vogliono essere vicini alle attrazioni turistiche. Per la sua importanza storica \u00e8 menzionata in molti scritti glagolitici ed \u00e8 diventata la dimora di molti nuovi residenti che apprezzano l&#8217;autenticit\u00e0, la bellezza e la pace di questo luogo costiero.<\/p>\n<p>Terreno edificabile con una superficie di 989,8 m2 con un progetto presentato per l&#8217;ottenimento del permesso di costruire. Ognuna delle due unit\u00e0 abitative di questa villa di lusso dispone di piscina privata, terrazza esterna coperta, giardino, diversi posti auto e cantina.<\/p>\n<p>La casa C1 copre complessivamente 231,18 m2 di superficie abitabile. Al piano terra si trovano una cucina, un soggiorno e una camera con bagno, mentre al primo piano di 69,68 mq ci sono camere, due bagni, oltre ad un terrazzo coperto con vista mare.<br \/>\nLa casa C2 ha un totale di 232,12 m2 di superficie abitabile. Al piano terra, sono 99,60 mq, hanno una cucina, un soggiorno e una camera con bagno, mentre al primo piano di 70,30 mq ci sono altre tre camere e due bagni.<\/p>\n<p>Cari clienti, secondo la legge sulla mediazione nelle transazioni immobiliari, la visione dell&#039;immobile \u00e8 possibile solo previa firma del contratto di mediazione. Secondo quanto previsto dallo stesso, in caso di acquisto l&#039;acquirente \u00e8 tenuto a pagare la commissione d&#039;agenzia.<\/p>\n<p>CODICE ID: 2173<\/p>\n<p>Sendi Vinski<br \/>\nAgente autorizzato<br \/>\nCellulare: 0038598443289<br \/>\nTelefono: 0038551222673<br \/>\nE-mail: prodaja@ardor-realestate.com<br \/>\nwww.ardor-realestate.com<\/p><\/div>\n<div id=\"nemacki\">Die Insel Krk, Tribulje, ein Ort, \u00fcber dessen Sch\u00f6nheit seit dem Ende des 15. Jahrhunderts gesprochen wird, war schon immer ein Zufluchtsort f\u00fcr eengenijen die Ruhe und Frieden suchen und dennochen sein der N\u00e4he von Touristenattractionen sein m\u00f6chten. Due to seiner historischen Bedeutung wird es in vielen glagolitischen Schriften geworden und ist zur Heimat vieler neuer Bewohner geworden, die die Authenzitit\u00e4t, Sch\u00f6nheit und Ruhe dieses Ortes am Meer zu st\u00e4tten wissen.<\/p>\n<p>Baugrundst\u00fcck mit einer Fl\u00e4che von 989,8 m2 mit einem zur Erlangung einer Baugenehmigung eingereichten Projekt. Jede der beiden Wohneinheiten dieser Luxusvilla verf\u00fcgt \u00fcber einen eigenen private Pool, eine \u00fcberdachte Au\u00dfenterrasse, einen Garten, mehrere Parkpl\u00e4tze und einen Keller.<\/p>\n<p>La Haus C1 dispone di una superficie abitabile totale di 231,18 m2. Im Erdgeschos gibt es eine K\u00fcche, ein Wohnzimmer und ein Schlafzimmer mit Bad, w\u00e4hrend sich im ersten Stock von 69.68 m2 zwei Zimmer, zwei Badezimmer sowie eine \u00fcberdachte Terrasse mit Blick auf das Meer befinden.<br \/>\nLa Haus C2 dispone di una superficie abitabile totale di 232,12 m2. Im Erdgeschoss gibt es auf 99.60 m2 eine K\u00fcche, ein Wohnzimmer und ein Schlafzimmer mit Bad, w\u00e4hrend im ersten Stock auf 70.30 m2 drei weiter Schlafzimmer und zwei Badezimmer liegen.<\/p>\n<p>Sehr geehrte Kunden, gem\u00e4\u00df dem Gesetz \u00fcber die Vermittlung bei Immobilientransactionen ist eine Immobilienbesichtigung nur mit der Unterzeichnung des Vermittlungsvertrags m\u00f6glich. Demnach ist der K\u00e4ufer im Falle eines Kaufes zur Zahlung der Vermittlungsprovision vermichtet.<\/p>\n<p>CODICE ID: 2173<\/p>\n<p>Sendi Vinski<br \/>\nAgente autorizzato<br \/>\nCellulare: 0038598443289<br \/>\nTelefono: 0038551222673<br \/>\nE-mail: prodaja@ardor-realestate.com<br \/>\nwww.ardor-realestate.com<\/p><\/div>\n<div id=\"slovenacki\">L&#039;isola di Veglia, Tribulje, una regione la cui bellezza \u00e8 stata decantata fin dalla fine del XV secolo, \u00e8 sempre stata un rifugio per chi cerca pace e tranquillit\u00e0 e desidera essere vicino alle attrazioni turistiche. Grazie alla sua importanza storica, \u00e8 stata menzionata in numerosi documenti scritti ed \u00e8 diventata la casa di molti nuovi residenti, che apprezzano l&#039;autenticit\u00e0, la bellezza e la pace di questa regione costiera.<\/p>\n<p>Terreno edificabile di 989,8 m\u00b2 con progetto preliminare per l&#039;ottenimento del permesso di costruire. Ciascuna delle due unit\u00e0 abitative di questa lussuosa villa dispone di piscina privata, terrazza esterna coperta, giardino, diversi posti auto e cantina.<\/p>\n<p>La casa C1 ha una superficie abitabile totale di 231,18 m\u00b2. Al piano terra si trovano una cucina, un soggiorno e una camera da letto con bagno, mentre al primo piano, di 69,68 m\u00b2, si trovano due camere, due bagni e una terrazza coperta con vista mare.<br \/>\nLa casa C2 ha una superficie abitabile totale di 232,12 m\u00b2. Al piano terra di 99,60 m\u00b2 si trovano una cucina, un soggiorno e una camera da letto con bagno, mentre al primo piano di 70,30 m\u00b2 si trovano altre tre camere da letto e due bagni.<\/p>\n<p>Cari clienti, ai sensi della legge sull&#039;intermediazione immobiliare, la visione di un immobile \u00e8 possibile solo previa sottoscrizione di un contratto di mediazione. Secondo quanto previsto dallo stesso, in caso di acquisto l&#039;acquirente \u00e8 tenuto a pagare una commissione d&#039;agenzia.<\/p>\n<p>CODICE ID: 2173<\/p>\n<p>Sendi Vinski<br \/>\nAgente autorizzato<br \/>\nCellulare: 0038598443289<br \/>\nTelefono: 0038551222673<br \/>\nE-mail: prodaja@ardor-realestate.com<br \/>\nwww.ardor-realestate.com<\/p><\/div>","protected":false},"excerpt":{"rendered":"<p>Otok Krk, Tribulje, mjesto o \u010dijoj se ljepoti pri\u010da jo\u0161 od kraja 15. stolje\u0107a, oduvijek je bilo uto\u010di\u0161te za one koji tra\u017ee mir i ti\u0161inu, a ipak \u017eele biti blizu turisti\u010dkih sadr\u017eaja. Svojom povijesnom va\u017eno\u0161\u0107u, spominje se u mnogim glagolja\u0161kim spisima te je postalo dom mnogim novim stanovnicima koji cijene autenti\u010dnost, ljepotu i mir ovog [&hellip;]<\/p>","protected":false},"author":0,"featured_media":33933,"parent":0,"menu_order":0,"template":"","property_type":[66],"property_status":[255],"property_feature":[],"property_label":[745,538],"property_country":[104],"property_state":[555],"property_city":[314,765],"property_area":[199],"class_list":["post-33244","property","type-property","status-publish","has-post-thumbnail","hentry","property_type-zemljiste","property_status-za-prodaju","property_label-gradevinsko","property_label-investicije","property_country-hrvatska","property_state-tribulje","property_city-dobrinj","property_city-tribulje-dobrinj","property_area-primorsko-goranska-zupanija"],"property_meta":{"_thumbnail_id":["33933"],"fave_komunalije":["Voda","Struja","Gradski vodovod","Asfaltni put","Gradska kanalizacija",""],"fave_blizina-sadrzaja":["Park","Sportski centar","Igrali\u0161te","Po\u0161ta","Banka","Vrti\u0107","Trgovina","\u0160kola","Javni prijevoz","Blizina mora",""],"fave_namjena":["stambeno",""],"fave_tip-zemljista":["gra\u0111evinsko",""],"fave_property_id":["2173"],"fave_property_price":["298000"],"fave_property_rooms":[""],"fave_property_bedrooms":[""],"fave_property_bathrooms":[""],"fave_property_size":["989.80"],"houzez_geolocation_long":["14.5848327"],"houzez_geolocation_lat":["45.1380903"],"fave_sprat":[""],"fave_lokacija":["Tribulje, Dobrinj"],"fave_wc":[""],"fave_ukupno-katova":[""],"fave_property_land_postfix":["m\u00b2"],"fave_property_size_prefix":["m\u00b2"],"fave_property_land":["0.00"],"fave_grijanje":[""],"fave_energetski-razred":[""],"fave_property_year":[""],"fave_dozvole":[""],"fave_tehnika":[""],"fave_parkirna-mjesta":[""],"fave_vrt":[""],"fave_property_images":["33236","33233","33234","33231","33230","33232","33237","33238","33245","15913","15913","15913","15913","15913","15913","15913","15913","15913","15913","15913","15913","15913","15913","15913","15913","15913","15913","15913","15913","15913","15913","15913","15913","15913","15913","15913","15913","15913","15913","15913","15913","15913","15913","15913","15913","15913","15913","15913","15913"],"fave_garaza":[""],"fave_natkriveno-parkirno-mjesto":[""],"fave_broj-etaza":[""],"fave_pozicija":[""],"fave_tip-kuce":[""],"fave_tip-stana":[""],"fave_property_location":["45.1380903,14.5848327"],"fave_property_map":["1"],"fave_lokacija-2":["Tribulje, Dobrinj"],"fave_agent_display_option":["agent_info"],"fave_agents":["prodaja@ardor-realestate.com"],"_wp_page_template":["default"],"rank_math_internal_links_processed":["1"],"houzez_total_property_views":["1092"],"houzez_views_by_date":["a:61:{s:10:\"03-04-2026\";i:2;s:10:\"03-05-2026\";i:8;s:10:\"03-06-2026\";i:3;s:10:\"03-07-2026\";i:2;s:10:\"03-08-2026\";i:14;s:10:\"03-09-2026\";i:1;s:10:\"03-10-2026\";i:8;s:10:\"03-13-2026\";i:3;s:10:\"03-14-2026\";i:17;s:10:\"03-17-2026\";i:8;s:10:\"03-18-2026\";i:10;s:10:\"03-19-2026\";i:17;s:10:\"03-20-2026\";i:8;s:10:\"03-21-2026\";i:8;s:10:\"03-22-2026\";i:8;s:10:\"03-23-2026\";i:1;s:10:\"03-24-2026\";i:8;s:10:\"03-25-2026\";i:1;s:10:\"03-26-2026\";i:9;s:10:\"03-27-2026\";i:7;s:10:\"03-29-2026\";i:14;s:10:\"03-30-2026\";i:8;s:10:\"03-31-2026\";i:1;s:10:\"04-01-2026\";i:7;s:10:\"04-04-2026\";i:15;s:10:\"04-05-2026\";i:1;s:10:\"04-06-2026\";i:8;s:10:\"04-07-2026\";i:16;s:10:\"04-08-2026\";i:8;s:10:\"04-09-2026\";i:9;s:10:\"04-10-2026\";i:3;s:10:\"04-11-2026\";i:7;s:10:\"04-12-2026\";i:9;s:10:\"04-13-2026\";i:7;s:10:\"04-14-2026\";i:8;s:10:\"04-15-2026\";i:1;s:10:\"04-16-2026\";i:9;s:10:\"04-17-2026\";i:11;s:10:\"04-18-2026\";i:14;s:10:\"04-19-2026\";i:1;s:10:\"04-20-2026\";i:7;s:10:\"04-21-2026\";i:1;s:10:\"04-22-2026\";i:11;s:10:\"04-23-2026\";i:7;s:10:\"04-24-2026\";i:1;s:10:\"04-25-2026\";i:8;s:10:\"04-26-2026\";i:8;s:10:\"04-27-2026\";i:7;s:10:\"04-28-2026\";i:11;s:10:\"04-29-2026\";i:10;s:10:\"04-30-2026\";i:7;s:10:\"05-01-2026\";i:7;s:10:\"05-02-2026\";i:16;s:10:\"05-04-2026\";i:8;s:10:\"05-06-2026\";i:8;s:10:\"05-07-2026\";i:7;s:10:\"05-08-2026\";i:8;s:10:\"05-09-2026\";i:19;s:10:\"05-11-2026\";i:7;s:10:\"05-12-2026\";i:1;s:10:\"05-13-2026\";i:1;}"],"houzez_recently_viewed":["2026-05-13 10:35:37"]},"_links":{"self":[{"href":"https:\/\/ardor-realestate.com\/it\/wp-json\/wp\/v2\/properties\/33244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ardor-realestate.com\/it\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/ardor-realestate.com\/it\/wp-json\/wp\/v2\/types\/property"}],"version-history":[{"count":0,"href":"https:\/\/ardor-realestate.com\/it\/wp-json\/wp\/v2\/properties\/33244\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ardor-realestate.com\/it\/wp-json\/wp\/v2\/media\/33933"}],"wp:attachment":[{"href":"https:\/\/ardor-realestate.com\/it\/wp-json\/wp\/v2\/media?parent=33244"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/ardor-realestate.com\/it\/wp-json\/wp\/v2\/property_type?post=33244"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/ardor-realestate.com\/it\/wp-json\/wp\/v2\/property_status?post=33244"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/ardor-realestate.com\/it\/wp-json\/wp\/v2\/property_feature?post=33244"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/ardor-realestate.com\/it\/wp-json\/wp\/v2\/property_label?post=33244"},{"taxonomy":"property_country","embeddable":true,"href":"https:\/\/ardor-realestate.com\/it\/wp-json\/wp\/v2\/property_country?post=33244"},{"taxonomy":"property_state","embeddable":true,"href":"https:\/\/ardor-realestate.com\/it\/wp-json\/wp\/v2\/property_state?post=33244"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/ardor-realestate.com\/it\/wp-json\/wp\/v2\/property_city?post=33244"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/ardor-realestate.com\/it\/wp-json\/wp\/v2\/property_area?post=33244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}